{"id":330,"count":0,"description":"","link":"https:\/\/parkingleipzig.de\/cs\/tag\/hippokrates-cs\/","name":"hippokrates","slug":"hippokrates-cs","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/parkingleipzig.de\/cs\/wp-json\/wp\/v2\/tags\/330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/parkingleipzig.de\/cs\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/parkingleipzig.de\/cs\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/parkingleipzig.de\/cs\/wp-json\/wp\/v2\/posts?tags=330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}